{"id":4175,"date":"2026-07-15T14:47:56","date_gmt":"2026-07-15T14:47:56","guid":{"rendered":"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/15\/violencia-interna-desata-caos-en-concentracion-argentina-en-atlanta-antes-de-semifinal-mundialista\/"},"modified":"2026-07-15T20:47:59","modified_gmt":"2026-07-15T20:47:59","slug":"violencia-interna-desata-caos-en-concentracion-argentina-en-atlanta-antes-de-semifinal-mundialista","status":"publish","type":"post","link":"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/15\/violencia-interna-desata-caos-en-concentracion-argentina-en-atlanta-antes-de-semifinal-mundialista\/","title":{"rendered":"Violencia interna desata caos en concentraci\u00f3n argentina en Atlanta antes de semifinal mundialista"},"content":{"rendered":"<p>Horas antes del esperado partido entre Argentina e Inglaterra en el Mundial 2026, una pelea entre hinchas argentinos en Atlanta desat\u00f3 un episodio de violencia que termin\u00f3 con tres detenidos y la intervenci\u00f3n inmediata de las fuerzas de seguridad.  <\/p>\n<p>El conflicto se origin\u00f3 en una concentraci\u00f3n de seguidores argentinos, donde una discusi\u00f3n verbal entre barras de San Lorenzo y Hurac\u00e1n escal\u00f3 r\u00e1pidamente a golpes, lanzamiento de sillas y tablones, generando un ambiente de caos y descontrol. Este incidente ocurri\u00f3 mientras las autoridades se enfocaban en evitar enfrentamientos entre las aficiones de Argentina e Inglaterra, para lo cual hab\u00edan dispuesto zonas separadas en el estadio.  <\/p>\n<p>Seg\u00fan reportaron las cadenas TYC y Ol\u00e9, el enfrentamiento tuvo antecedentes en provocaciones a trav\u00e9s de redes sociales, donde se recordaron episodios violentos previos, como los ocurridos en el Mundial de 2018. En la concentraci\u00f3n participaron barras de diversos clubes argentinos, entre ellos Racing, Excursionistas, Barracas Central, Almirante Brown, Belgrano e Independiente Rivadavia, reflejando la diversidad y complejidad de las pe\u00f1as que acompa\u00f1an a la selecci\u00f3n nacional.  <\/p>\n<p>La polic\u00eda actu\u00f3 con rapidez para controlar la situaci\u00f3n y detuvo a tres agresores. Las autoridades informaron que quienes sean identificados y culpables enfrentar\u00e1n una prohibici\u00f3n permanente para ingresar a cualquier estadio del pa\u00eds, una medida que busca frenar la violencia en el f\u00fatbol argentino. Cabe destacar que algunos de los detenidos ya contaban con prohibiciones previas que se hab\u00edan levantado antes del Mundial.  <\/p>\n<p>Este episodio ha encendido las alarmas entre los organizadores del torneo, quienes ahora deben redoblar esfuerzos para prevenir no solo posibles enfrentamientos entre las hinchadas de Argentina e Inglaterra, sino tambi\u00e9n la violencia interna entre las propias pe\u00f1as argentinas. En un contexto donde el deporte deber\u00eda ser un espacio de uni\u00f3n y celebraci\u00f3n, estos hechos evidencian la necesidad de pol\u00edticas m\u00e1s efectivas para garantizar la seguridad y la convivencia pac\u00edfica en los eventos deportivos.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/DiarioOle\/status\/2077352219188293781?s=20\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Horas antes del esperado partido entre Argentina e Inglaterra en el Mundial 2026, una pelea entre hinchas argentinos en Atlanta desat\u00f3 un episodio de violencia que termin\u00f3 con tres detenidos y la intervenci\u00f3n inmediata de las fuerzas de seguridad. El conflicto se origin\u00f3 en una concentraci\u00f3n de seguidores argentinos, donde una discusi\u00f3n verbal entre barras&#8230;<a class=\"btnReadMore\" href=\"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/15\/violencia-interna-desata-caos-en-concentracion-argentina-en-atlanta-antes-de-semifinal-mundialista\/\"> Ver M\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":4174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":1,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":4176,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions\/4176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4174"}],"wp:attachment":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}