{"id":4052,"date":"2026-07-14T16:54:05","date_gmt":"2026-07-14T16:54:05","guid":{"rendered":"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/14\/trump-obligado-a-pagar-5-6-millones-de-dolares-a-e-jean-carroll-por-abuso-sexual-y-difamacion\/"},"modified":"2026-07-14T22:54:06","modified_gmt":"2026-07-14T22:54:06","slug":"trump-obligado-a-pagar-5-6-millones-de-dolares-a-e-jean-carroll-por-abuso-sexual-y-difamacion","status":"publish","type":"post","link":"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/14\/trump-obligado-a-pagar-5-6-millones-de-dolares-a-e-jean-carroll-por-abuso-sexual-y-difamacion\/","title":{"rendered":"Trump obligado a pagar 5.6 millones de d\u00f3lares a E. Jean Carroll por abuso sexual y difamaci\u00f3n"},"content":{"rendered":"<p>El presidente Donald Trump fue obligado a desembolsar m\u00e1s de 5.6 millones de d\u00f3lares a la escritora neoyorquina E. Jean Carroll, m\u00e1s de tres a\u00f1os despu\u00e9s de que un jurado civil federal lo declarara responsable de abuso sexual y difamaci\u00f3n. El pago, que incluye intereses, se realiz\u00f3 el martes 14 de julio de 2026, seg\u00fan los registros judiciales, poniendo fin a una prolongada batalla legal que Trump ha intentado retrasar mediante apelaciones.  <\/p>\n<p>La controversia se remonta a una denuncia presentada por Carroll, quien acus\u00f3 a Trump de agredirla sexualmente en un probador de una tienda departamental durante la d\u00e9cada de 1990. Posteriormente, en 2022, Trump neg\u00f3 p\u00fablicamente las acusaciones, calific\u00e1ndolas de &#8220;enga\u00f1o&#8221;, lo que deriv\u00f3 en una demanda por difamaci\u00f3n.  <\/p>\n<p>El caso alcanz\u00f3 un punto decisivo cuando la Corte Suprema de Estados Unidos rechaz\u00f3 el 29 de junio de 2026 revisar la apelaci\u00f3n de Trump, lo que permiti\u00f3 a Carroll solicitar al tribunal de primera instancia en Manhattan que ordenara el pago del juicio, que originalmente ascend\u00eda a 5 millones de d\u00f3lares m\u00e1s intereses. Un juez federal, Lewis A. Kaplan \u2014designado por Bill Clinton\u2014, dictamin\u00f3 el 8 de julio que Trump deb\u00eda cumplir con la sentencia y dejar de retrasar el proceso. En su fallo, Kaplan se\u00f1al\u00f3 que &#8220;es hora de que &#8216;haga justicia&#8217; y pague el juicio&#8221;.  <\/p>\n<p>Este caso se suma a otro juicio civil en Manhattan, donde en 2024 un jurado otorg\u00f3 a Carroll 83.3 millones de d\u00f3lares por difamaci\u00f3n, tras concluir que Trump la difam\u00f3 en 2019 al negar por primera vez sus acusaciones. La apelaci\u00f3n de Trump en ese proceso a\u00fan est\u00e1 en curso.  <\/p>\n<p>La resoluci\u00f3n de este litigio representa un precedente importante en la lucha contra la impunidad de figuras p\u00fablicas acusadas de abuso y difamaci\u00f3n, y subraya la importancia de que el sistema judicial act\u00fae con celeridad y firmeza frente a intentos de dilaci\u00f3n. En un contexto donde los derechos civiles y la justicia social exigen mayor protecci\u00f3n para las v\u00edctimas, la decisi\u00f3n judicial contra Trump marca un paso relevante hacia la rendici\u00f3n de cuentas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump fue obligado a desembolsar m\u00e1s de 5.6 millones de d\u00f3lares a la escritora neoyorquina E. Jean Carroll, m\u00e1s de tres a\u00f1os despu\u00e9s de que un jurado civil federal lo declarara responsable de abuso sexual y difamaci\u00f3n. El pago, que incluye intereses, se realiz\u00f3 el martes 14 de julio de 2026, seg\u00fan&#8230;<a class=\"btnReadMore\" href=\"https:\/\/la-linea.com.mx\/index.php\/2026\/07\/14\/trump-obligado-a-pagar-5-6-millones-de-dolares-a-e-jean-carroll-por-abuso-sexual-y-difamacion\/\"> Ver M\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":4051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4052"}],"version-history":[{"count":1,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4052\/revisions"}],"predecessor-version":[{"id":4053,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4052\/revisions\/4053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4051"}],"wp:attachment":[{"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-linea.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}